{"id":10804,"date":"2019-02-22T20:49:54","date_gmt":"2019-02-22T19:49:54","guid":{"rendered":"http:\/\/fefac.cat\/empresarial\/?p=10804"},"modified":"2021-11-19T18:31:04","modified_gmt":"2021-11-19T17:31:04","slug":"comunicat-del-departament-sobre-els-serveis-de-la-plataforma-tecnologica-luda","status":"publish","type":"post","link":"https:\/\/fefac.cat\/empresarial\/comunicat-del-departament-sobre-els-serveis-de-la-plataforma-tecnologica-luda\/","title":{"rendered":"Comunicat del Departament de Salut sobre els serveis de la plataforma tecnol\u00f2gica Luda"},"content":{"rendered":"<p>El Departament de Salut ha enviat un <a href=\"https:\/\/fefac.cat\/empresarial\/wp-content\/uploads\/2019\/02\/Comunicat-sobre-LUDA.pdf\">comunicat<\/a> informant que <strong>qualsevol farm\u00e0cia comunit\u00e0ria<\/strong> <strong>que s&#8217;adhereixi<\/strong> a la plataforma tecnol\u00f2gica <strong>Luda<\/strong> podria estar <strong>incomplint la normativa<\/strong> sobre venda a dist\u00e0ncia de medicaments.<\/p>\n<p>En el comunicat, el Servei d&#8217;Ordenaci\u00f3 i Qualitat Farmac\u00e8utiques explica que ha rebut <strong>diferents consultes<\/strong> per part d&#8217;institucions i col\u00b7legis professionals, -la Federaci\u00f3 d&#8217;Associacions de Farm\u00e0cies de Catalunya (<strong>FEFAC<\/strong>) ha estat una d&#8217;elles-, envers els serveis que ofereix la plataforma Luda a les farm\u00e0cies comunit\u00e0ries de Catalunya.<\/p>\n<p><a href=\"https:\/\/fefac.cat\/empresarial\/wp-content\/uploads\/2019\/02\/Comunicat-sobre-LUDA.pdf\">Comunicat sobre LUDA<\/a><\/p>\n<p><strong>Not\u00edcia relacionada<\/strong>:<a href=\"https:\/\/fefac.cat\/empresarial\/lassessor-respon-es-legal-lactivitat-de-luda\/\"> L&#8217;assessor respon: \u00c9s legal l&#8217;activitat de Luda?<\/a><\/p>\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Departament de Salut ha enviat un comunicat informant que qualsevol farm\u00e0cia comunit\u00e0ria que s&#8217;adhereixi a la plataforma tecnol\u00f2gica Luda podria estar incomplint la normativa sobre venda a dist\u00e0ncia de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"off","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[2066,11,294],"tags":[1860,2077],"class_list":["post-10804","post","type-post","status-publish","format-standard","hentry","category-categoria-actualitat","category-fefac","category-politica-sanitaria","tag-luda","tag-venda-a-distancia"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Comunicat del Departament de Salut sobre els serveis de la plataforma tecnol\u00f2gica Luda - FEFAC<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/fefac.cat\/empresarial\/comunicat-del-departament-sobre-els-serveis-de-la-plataforma-tecnologica-luda\/\" \/>\n<meta property=\"og:locale\" content=\"ca_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Comunicat del Departament de Salut sobre els serveis de la plataforma tecnol\u00f2gica Luda - FEFAC\" \/>\n<meta property=\"og:description\" content=\"El Departament de Salut ha enviat un comunicat informant que qualsevol farm\u00e0cia comunit\u00e0ria que s&#8217;adhereixi a la plataforma tecnol\u00f2gica Luda podria estar incomplint la normativa sobre venda a dist\u00e0ncia de [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/fefac.cat\/empresarial\/comunicat-del-departament-sobre-els-serveis-de-la-plataforma-tecnologica-luda\/\" \/>\n<meta property=\"og:site_name\" content=\"FEFAC\" \/>\n<meta property=\"article:published_time\" content=\"2019-02-22T19:49:54+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-11-19T17:31:04+00:00\" \/>\n<meta name=\"author\" content=\"qabh859\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrit per\" \/>\n\t<meta name=\"twitter:data1\" content=\"qabh859\" \/>\n\t<meta name=\"twitter:label2\" content=\"Temps estimat de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minut\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/fefac.cat\\\/empresarial\\\/comunicat-del-departament-sobre-els-serveis-de-la-plataforma-tecnologica-luda\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fefac.cat\\\/empresarial\\\/comunicat-del-departament-sobre-els-serveis-de-la-plataforma-tecnologica-luda\\\/\"},\"author\":{\"name\":\"qabh859\",\"@id\":\"https:\\\/\\\/fefac.cat\\\/empresarial\\\/#\\\/schema\\\/person\\\/03012b2506772bd65738ce781a3947f7\"},\"headline\":\"Comunicat del Departament de Salut sobre els serveis de la plataforma tecnol\u00f2gica Luda\",\"datePublished\":\"2019-02-22T19:49:54+00:00\",\"dateModified\":\"2021-11-19T17:31:04+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/fefac.cat\\\/empresarial\\\/comunicat-del-departament-sobre-els-serveis-de-la-plataforma-tecnologica-luda\\\/\"},\"wordCount\":121,\"keywords\":[\"luda\",\"venda a dist\u00e0ncia\"],\"articleSection\":[\"Actualitat\",\"FEFAC\",\"Pol\u00edtica sanit\u00e0ria\"],\"inLanguage\":\"ca\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/fefac.cat\\\/empresarial\\\/comunicat-del-departament-sobre-els-serveis-de-la-plataforma-tecnologica-luda\\\/\",\"url\":\"https:\\\/\\\/fefac.cat\\\/empresarial\\\/comunicat-del-departament-sobre-els-serveis-de-la-plataforma-tecnologica-luda\\\/\",\"name\":\"Comunicat del Departament de Salut sobre els serveis de la plataforma tecnol\u00f2gica Luda - FEFAC\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fefac.cat\\\/empresarial\\\/#website\"},\"datePublished\":\"2019-02-22T19:49:54+00:00\",\"dateModified\":\"2021-11-19T17:31:04+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/fefac.cat\\\/empresarial\\\/#\\\/schema\\\/person\\\/03012b2506772bd65738ce781a3947f7\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/fefac.cat\\\/empresarial\\\/comunicat-del-departament-sobre-els-serveis-de-la-plataforma-tecnologica-luda\\\/#breadcrumb\"},\"inLanguage\":\"ca\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/fefac.cat\\\/empresarial\\\/comunicat-del-departament-sobre-els-serveis-de-la-plataforma-tecnologica-luda\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/fefac.cat\\\/empresarial\\\/comunicat-del-departament-sobre-els-serveis-de-la-plataforma-tecnologica-luda\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/fefac.cat\\\/empresarial\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Comunicat del Departament de Salut sobre els serveis de la plataforma tecnol\u00f2gica Luda\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/fefac.cat\\\/empresarial\\\/#website\",\"url\":\"https:\\\/\\\/fefac.cat\\\/empresarial\\\/\",\"name\":\"FEFAC\",\"description\":\"Federaci\u00f3 d&#039;Associacions de Farm\u00e0cies de Catalunya\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/fefac.cat\\\/empresarial\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ca\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/fefac.cat\\\/empresarial\\\/#\\\/schema\\\/person\\\/03012b2506772bd65738ce781a3947f7\",\"name\":\"qabh859\",\"url\":\"https:\\\/\\\/fefac.cat\\\/empresarial\\\/author\\\/qabh859\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Comunicat del Departament de Salut sobre els serveis de la plataforma tecnol\u00f2gica Luda - FEFAC","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/fefac.cat\/empresarial\/comunicat-del-departament-sobre-els-serveis-de-la-plataforma-tecnologica-luda\/","og_locale":"ca_ES","og_type":"article","og_title":"Comunicat del Departament de Salut sobre els serveis de la plataforma tecnol\u00f2gica Luda - FEFAC","og_description":"El Departament de Salut ha enviat un comunicat informant que qualsevol farm\u00e0cia comunit\u00e0ria que s&#8217;adhereixi a la plataforma tecnol\u00f2gica Luda podria estar incomplint la normativa sobre venda a dist\u00e0ncia de [&hellip;]","og_url":"https:\/\/fefac.cat\/empresarial\/comunicat-del-departament-sobre-els-serveis-de-la-plataforma-tecnologica-luda\/","og_site_name":"FEFAC","article_published_time":"2019-02-22T19:49:54+00:00","article_modified_time":"2021-11-19T17:31:04+00:00","author":"qabh859","twitter_card":"summary_large_image","twitter_misc":{"Escrit per":"qabh859","Temps estimat de lectura":"1 minut"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/fefac.cat\/empresarial\/comunicat-del-departament-sobre-els-serveis-de-la-plataforma-tecnologica-luda\/#article","isPartOf":{"@id":"https:\/\/fefac.cat\/empresarial\/comunicat-del-departament-sobre-els-serveis-de-la-plataforma-tecnologica-luda\/"},"author":{"name":"qabh859","@id":"https:\/\/fefac.cat\/empresarial\/#\/schema\/person\/03012b2506772bd65738ce781a3947f7"},"headline":"Comunicat del Departament de Salut sobre els serveis de la plataforma tecnol\u00f2gica Luda","datePublished":"2019-02-22T19:49:54+00:00","dateModified":"2021-11-19T17:31:04+00:00","mainEntityOfPage":{"@id":"https:\/\/fefac.cat\/empresarial\/comunicat-del-departament-sobre-els-serveis-de-la-plataforma-tecnologica-luda\/"},"wordCount":121,"keywords":["luda","venda a dist\u00e0ncia"],"articleSection":["Actualitat","FEFAC","Pol\u00edtica sanit\u00e0ria"],"inLanguage":"ca"},{"@type":"WebPage","@id":"https:\/\/fefac.cat\/empresarial\/comunicat-del-departament-sobre-els-serveis-de-la-plataforma-tecnologica-luda\/","url":"https:\/\/fefac.cat\/empresarial\/comunicat-del-departament-sobre-els-serveis-de-la-plataforma-tecnologica-luda\/","name":"Comunicat del Departament de Salut sobre els serveis de la plataforma tecnol\u00f2gica Luda - FEFAC","isPartOf":{"@id":"https:\/\/fefac.cat\/empresarial\/#website"},"datePublished":"2019-02-22T19:49:54+00:00","dateModified":"2021-11-19T17:31:04+00:00","author":{"@id":"https:\/\/fefac.cat\/empresarial\/#\/schema\/person\/03012b2506772bd65738ce781a3947f7"},"breadcrumb":{"@id":"https:\/\/fefac.cat\/empresarial\/comunicat-del-departament-sobre-els-serveis-de-la-plataforma-tecnologica-luda\/#breadcrumb"},"inLanguage":"ca","potentialAction":[{"@type":"ReadAction","target":["https:\/\/fefac.cat\/empresarial\/comunicat-del-departament-sobre-els-serveis-de-la-plataforma-tecnologica-luda\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/fefac.cat\/empresarial\/comunicat-del-departament-sobre-els-serveis-de-la-plataforma-tecnologica-luda\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/fefac.cat\/empresarial\/"},{"@type":"ListItem","position":2,"name":"Comunicat del Departament de Salut sobre els serveis de la plataforma tecnol\u00f2gica Luda"}]},{"@type":"WebSite","@id":"https:\/\/fefac.cat\/empresarial\/#website","url":"https:\/\/fefac.cat\/empresarial\/","name":"FEFAC","description":"Federaci\u00f3 d&#039;Associacions de Farm\u00e0cies de Catalunya","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/fefac.cat\/empresarial\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ca"},{"@type":"Person","@id":"https:\/\/fefac.cat\/empresarial\/#\/schema\/person\/03012b2506772bd65738ce781a3947f7","name":"qabh859","url":"https:\/\/fefac.cat\/empresarial\/author\/qabh859\/"}]}},"_links":{"self":[{"href":"https:\/\/fefac.cat\/empresarial\/wp-json\/wp\/v2\/posts\/10804","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fefac.cat\/empresarial\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fefac.cat\/empresarial\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fefac.cat\/empresarial\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/fefac.cat\/empresarial\/wp-json\/wp\/v2\/comments?post=10804"}],"version-history":[{"count":0,"href":"https:\/\/fefac.cat\/empresarial\/wp-json\/wp\/v2\/posts\/10804\/revisions"}],"wp:attachment":[{"href":"https:\/\/fefac.cat\/empresarial\/wp-json\/wp\/v2\/media?parent=10804"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fefac.cat\/empresarial\/wp-json\/wp\/v2\/categories?post=10804"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fefac.cat\/empresarial\/wp-json\/wp\/v2\/tags?post=10804"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}