{"id":14873,"date":"2019-07-15T10:38:00","date_gmt":"2019-07-15T08:38:00","guid":{"rendered":"http:\/\/fefac.cat\/empresarial\/?p=14873"},"modified":"2019-07-15T10:40:50","modified_gmt":"2019-07-15T08:40:50","slug":"dubtes-sobre-legalitat-entregoo-roger-canals-arco-rp","status":"publish","type":"post","link":"https:\/\/fefac.cat\/empresarial\/dubtes-sobre-legalitat-entregoo-roger-canals-arco-rp\/","title":{"rendered":"Dubtes sobre la legalitat d&#8217;Entregoo, una altra aplicaci\u00f3 d&#8217;enviament de medicaments."},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">Roger Canals, advocat de la FEFAC, parla a Correo Farmac\u00e9utico de la venda a dist\u00e0ncia de medicaments.<\/h2>\n\n\n\n<p>Entregoo \u00e9s una app d&#8217;entrega de medicaments i productes de parafarm\u00e0cia a domicili que ofereix, previ registre en la seva app, el servei de tramitaci\u00f3, recollida en farm\u00e0cia i lliurament en el domicili de l&#8217;usuari de medicaments, amb recepta m\u00e8dica o sense, aix\u00ed com productes de parafarm\u00e0cia.<\/p>\n\n\n\n<p>Aquest sistema est\u00e0 dirigit a persones que busquen una manera pr\u00e0ctica d&#8217;obtenir les medicines o productes de parafarm\u00e0cia en un lloc i hora concertats, i a persones grans amb dificultats de mobilitat, persones dependents, accidentades o sense capacitat de despla\u00e7ament.<\/p>\n\n\n\n<p><strong>Sobre la venda a dist\u00e0ncia de medicaments<\/strong><\/p>\n\n\n\n<p>En aquest article publicat a Correo Farmac\u00e9utico, Roger Canals, advocat de la FEFAC, parla de la normativa actual, que prohibeix la venda a dist\u00e0ncia de medicaments, excepte si aquesta es realitza a trav\u00e9s de les webs de les farm\u00e0cies oficials homologades amb el s\u00edmbol corresponent, de conformitat amb el RD 870\/2013.  Canals comenta que aquest RD estableix una s\u00e8rie de requisits: de transport, dispensaci\u00f3 i consell farmac\u00e8utic.<\/p>\n\n\n\n<p><strong>Atenci\u00f3 directa<\/strong><\/p>\n\n\n\n<p>Canals explica que amb &#8216;Entregoo&#8217; hi ha un problema d&#8217;intermediari. Actualment un farmac\u00e8utic no pot recollir un medicament i entregar-li a la ve\u00efna del cinqu\u00e8 pis. &#8220;Si un llicenciat no pot fer-ho, segons la normativa, em resisteixo a pensar que es pugui fer a trav\u00e9s d&#8217;un missatger&#8221;, concreta Canals.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><strong>Llegeix la not\u00edcia sencera a Correo Farmac\u00e9utico:<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-embed-wordpress wp-block-embed is-type-wp-embed is-provider-correo-farmaceutico\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"wp-embedded-content\" data-secret=\"RVqszTYg0O\"><a href=\"https:\/\/www.correofarmaceutico.com\/profesion\/farmacia-comunitaria\/dudas-sobre-la-legalidad-de-entregoo-otra-aplicacion-de-envio-de-medicamentos.html\">Dudas sobre la legalidad de \u2018Entregoo\u2019, otra aplicaci\u00f3n de env\u00edo de medicamentos<\/a><\/blockquote><iframe title=\"&#8220;Dudas sobre la legalidad de \u2018Entregoo\u2019, otra aplicaci\u00f3n de env\u00edo de medicamentos&#8221; &#8212; Correo Farmaceutico\" class=\"wp-embedded-content lazyload\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; clip: rect(1px, 1px, 1px, 1px);\" data-src=\"https:\/\/www.correofarmaceutico.com\/profesion\/farmacia-comunitaria\/dudas-sobre-la-legalidad-de-entregoo-otra-aplicacion-de-envio-de-medicamentos.html\/embed#?secret=RVqszTYg0O\" data-secret=\"RVqszTYg0O\" width=\"600\" height=\"338\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" data-load-mode=\"1\"><\/iframe>\n<\/div><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Roger Canals, advocat de la FEFAC, parla a Correo Farmac\u00e9utico de la venda a dist\u00e0ncia de medicaments.<\/p>\n","protected":false},"author":2313,"featured_media":14876,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"off","_et_pb_old_content":"<!-- wp:paragraph -->\n<p><strong>S\u00f3n els serveis oferts per Luda adequats a les oficines de farm\u00e0cia dins del marc legal vigent relatiu a la distribuci\u00f3, dispensaci\u00f3 i \u00fas de medicaments i productes sanitaris?<\/strong><\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Luda \u00e9s una societat de nova creaci\u00f3 que ha\ndesenvolupat una plataforma digital destinada a les oficines de farm\u00e0cia, amb\nl\u2019objectiu que tots els establiments farmac\u00e8utics que s\u2019adhereixin al sistema\nactu\u00efn en xarxa per donar compliment a dos serveis o funcions principals:<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:list -->\n<ul><li><strong>Servei d\u2019interconnexi\u00f3 entre oficines de farm\u00e0cia per tal de donar\ncobertura a desprove\u00efments i\/o falta d\u2019estocs de medicaments i productes\nsanitaris:<\/strong> Luda ofereix un sistema de connexi\u00f3 interna\nentre oficines de farm\u00e0cia a trav\u00e9s d\u2019una aplicaci\u00f3 inform\u00e0tica que permet\ncon\u00e8ixer la disponibilitat de medicaments en temps real en cadascuna de les\nfarm\u00e0cies adherides al sistema, amb l\u2019objectiu de cobrir el desprove\u00efment d\u2019un\ndeterminat medicament i con\u00e8ixer el seu nivell d\u2019estoc. El sistema funciona\naix\u00ed: un farmac\u00e8utic que est\u00e0 atenent a un pacient a qui no li pot dispensar un\nmedicament ja que no el t\u00e9 en estoc, podr\u00e0 consultar la disponibilitat del\nmedicament a trav\u00e9s d\u2019un llistat de farm\u00e0cies ordenades per proximitat i\nadherides a Luda. Si el pacient ho desitja, el farmac\u00e8utic podr\u00e0 reservar-lo a\ntrav\u00e9s de la plataforma a la farm\u00e0cia que esculli el pacient, que anir\u00e0 a\nrecollir-lo a la farm\u00e0cia escollida.<\/li><\/ul>\n<!-- \/wp:list -->\n\n<!-- wp:list -->\n<ul><li><strong>Servei de compra online de medicaments i\/o productes sanitaris, a\ntrav\u00e9s de l\u2019aplicaci\u00f3 de LUDA: <\/strong>El pacient consulta la\ndisponibilitat del medicament a la farm\u00e0cia m\u00e9s propera, gestiona la reserva i\nsol\u00b7licita, si aix\u00ed ho estima, l\u2019entrega del medicament per mitj\u00e0 d\u2019un\nmissatger en la ubicaci\u00f3 i\/o domicili que designi. El farmac\u00e8utic rep a trav\u00e9s\ndel sistema la corresponent reserva del medicament, aix\u00ed com observacions i\/o\nconsultes plantejades pel pacient. D\u2019altra banda, Luda s\u2019encarrega de la\ntransacci\u00f3 econ\u00f2mica de la compra i la gesti\u00f3 del transport des de l\u2019oficina de\nfarm\u00e0cia seleccionada fins al lloc de dest\u00ed que indiqui l\u2019usuari.<\/li><\/ul>\n<!-- \/wp:list -->\n\n<!-- wp:paragraph -->\n<p><strong>Consideracions\njur\u00eddiques del servei de consulta de disponibilitat de medicaments entre\nfarm\u00e0cies<\/strong><\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>La connexi\u00f3 intranet del conjunt de farm\u00e0cies\na fi de consultar la disponibilitat d\u2019un medicament, i la possibilitat\nd\u2019efectuar-ne la reserva per tal que el pacient reculli a la farm\u00e0cia que si el\nt\u00e9 disponible \u00e9s una activitat que s\u2019adequa als principis de dispensaci\u00f3 i\natenci\u00f3 farmac\u00e8utica derivats <strong>de\nl\u2019article 3.5 del Reial Decret Legislatiu 1\/2015, de 24 de juliol<\/strong>, pel que\ns\u2019aprov\u00e0 el Text Ref\u00f3s de la Llei de garanties i \u00fas racional dels medicaments i\nproductes sanitaris (TRLMPS) regulador de la venda a dist\u00e0ncia i\/o a domicili\nde medicaments i productes sanitaris, estigui o no subjecta la seva dispensaci\u00f3\na prescripci\u00f3 m\u00e8dica.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>La xarxa permet un intercanvi d\u2019informaci\u00f3 entre farm\u00e0cies, sent el propi client qui finalment recollir\u00e0 el medicament a la farm\u00e0cia de dest\u00ed, presentant la corresponent recepta m\u00e8dica, en cas que el medicament requerit es trobi subjecte a prescripci\u00f3. La dispensaci\u00f3 es produeix de manera presencial i directa entre pacient i farmac\u00e8utic, i per tant la funci\u00f3 d\u2019atenci\u00f3 farmac\u00e8utica, aix\u00ed com el principi de dispensaci\u00f3 de medicaments, resulten garantits. <strong>Aquest servei resulta perfectament compatible amb la legislaci\u00f3 sectorial d\u2019aplicaci\u00f3.&nbsp; <\/strong><\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Nom\u00e9s deixar const\u00e0ncia que, en aplicaci\u00f3 de\nla nova regulaci\u00f3 en mat\u00e8ria de protecci\u00f3 de dades de car\u00e0cter personal, tant\nel tractament de dades personals facilitades pel client al farmac\u00e8utic\nd\u2019origen, com l\u2019eventual cessi\u00f3 d\u2019aquestes al farmac\u00e8utic de dest\u00ed, haurien de\nser objecte de protecci\u00f3, a fi i efecte de no inc\u00f3rrer en infraccions en aquest\n\u00e0mbit.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p><strong>Consideracions\njur\u00eddiques de la aplicaci\u00f3 online<\/strong><\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>El servei consistent en l\u2019adquisici\u00f3 de\nmedicaments a trav\u00e9s de l\u2019aplicaci\u00f3 Luda i la gesti\u00f3 d\u2019entrega d\u2019aquests a\ntrav\u00e9s de <strong>l\u2019aplicaci\u00f3 m\u00f2bil Luda s\u2019ha de\nqualificar com una venda de medicaments a dist\u00e0ncia i\/o per procediments\ntelem\u00e0tics,<\/strong> expressament prohibida per la normativa d\u2019aplicaci\u00f3 respecte\ndels medicaments subjectes a prescripci\u00f3 (Reial Decret Legislatiu 1\/2015, de 24\nde juliol) &nbsp;i limitada a les p\u00e0gines web\nde les oficines de farm\u00e0cia respecte dels medicaments no subjectes a prescripci\u00f3\nm\u00e8dica (Reial Decret 870\/2013).<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:list -->\n<ul><li>L\u2019article 3 del Reial Decret\n870\/2013 diu que \u00fanicament poden portar a terme la venda a dist\u00e0ncia de\nmedicaments mitjan\u00e7ant llocs web, les oficines de farm\u00e0cia obertes al p\u00fablic,\nlegalment autoritzades, que hagin efectuat la notificaci\u00f3 d\u2019aquesta activitat.\nL\u2019apartat segon d\u2019aquest article diu que la venda s\u2019ha de dur a terme amb la\nintervenci\u00f3 del farmac\u00e8utic, des de la seva oficina de farm\u00e0cia, previ\nassessorament personalitzat. L\u2019apartat tercer especifica que la venda&nbsp; de medicaments \u00fanicament es pot fer\ndirectament des de l\u2019oficina de farm\u00e0cia responsable de la dispensaci\u00f3, sense\nintervenci\u00f3 d\u2019intermediaris.<\/li><\/ul>\n<!-- \/wp:list -->\n\n<!-- wp:paragraph -->\n<p>L\u2019aplicaci\u00f3 desenvolupada per LUDA connecta\ntelem\u00e0ticament el pacient amb el farmac\u00e8utic, de manera que aquest \u00faltim rep la\nnotificaci\u00f3 de l\u2019enc\u00e0rrec del medicament i les observacions del pacient. En tal\nsentit, s\u2019observa que l\u2019aplicaci\u00f3 procura atendre el principi d\u2019atenci\u00f3\nfarmac\u00e8utica, no obstant, <strong>el sistema\ncreat per Luda topa amb el requisit inexcusable de no ser el lloc web de\nl\u2019oficina de farm\u00e0cia creat pel titular de l\u2019oficina de farm\u00e0cia.<\/strong><\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:list -->\n<ul><li>Al mateix temps, l\u2019article 11 del Reial Decret 870\/2013 estableix que el transport de medicaments i entrega a l\u2019usuari des de l\u2019oficina de farm\u00e0cia fins al domicili indicat per l\u2019usuari, ser\u00e0 responsabilitat de l\u2019oficina de farm\u00e0cia. El sistema proposat per Luda pel que fa al transport del medicament que el pacient encarregui a trav\u00e9s de l\u2019app m\u00f2bil comportaria un risc no assumible per les oficines de farm\u00e0cia, at\u00e8s que aquesta continuaria sent responsable del transport del medicament fins al pacient i de la correcta conservaci\u00f3 dels medicaments transportats fins al seu dest\u00ed.<\/li><\/ul>\n<!-- \/wp:list -->\n\n<!-- wp:paragraph -->\n<p>Per \u00faltim, l\u2019app m\u00f2bil d\u2019\u00fas particular permet alternativament, que sigui el propi pacient qui es desplaci fins a la farm\u00e0cia a recollir el medicament pr\u00e8viament adquirit a trav\u00e9s de l\u2019aplicaci\u00f3. En aquest escenari, <strong>l\u2019\u00fas de l\u2019aplicaci\u00f3 per cercar la disponibilitat d\u2019un determinat medicament a l\u2019oficina de farm\u00e0cia m\u00e9s propera i fer-ne la reserva, no comporta una venda a dist\u00e0ncia ni la vulneraci\u00f3 del principi de lliure elecci\u00f3 de farm\u00e0cia per part del pacient<\/strong> (Article 20.4k) de la Llei 31\/1991, de 13 de desembre, d\u2019Ordenaci\u00f3 Farmac\u00e8utica de Catalunya.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p><\/p>\n<!-- \/wp:paragraph -->\n\n<p><strong>Informaci\u00f3 extreta de la<\/strong><em> <a href=\"http:\/\/fefac.cat\/empresarial\/wp-content\/uploads\/2019\/02\/nota-legal-luda-1.pdf\" target=\"_blank\" rel=\"noreferrer noopener\" aria-label=\"&quot;Nota sobre el r\u00e8gim jur\u00eddic d'aplicaci\u00f3 dels serveis oferts per Luda a les oficines de farm\u00e0cia radicades a Catalunya&quot;  (abre en una nueva pesta\u00f1a)\">\"Nota sobre el r\u00e8gim jur\u00eddic d'aplicaci\u00f3 dels serveis oferts per Luda a les oficines de farm\u00e0cia radicades a Catalunya\" <\/a><\/em>elaborada per:<\/p>\n\n<!-- wp:image {\"width\":424,\"height\":104} -->\n<figure class=\"wp-block-image is-resized\"><img src=\"http:\/\/www.fefac.cat\/intranet\/noticies\/_userfiles\/images\/logos\/arco.jpg\" alt=\"\" width=\"424\" height=\"104\"\/><\/figure>\n<!-- \/wp:image -->\n\n<!-- wp:paragraph -->\n<p><strong>Not\u00edcies relacionades: <\/strong><a rel=\"noreferrer noopener\" aria-label=\"Comunicat del Departament de Salut sobre els serveis de la plataforma tecnol\u00f2gica Luda (abre en una nueva pesta\u00f1a)\" href=\"http:\/\/fefac.cat\/empresarial\/comunicat-del-departament-de-salut-sobre-els-serveis-de-la-plataforma-tecnologica-luda\/\" target=\"_blank\"><strong>Comunicat del Departament de Salut sobre els serveis de la plataforma tecnol\u00f2gica Luda<\/strong><\/a><\/p>\n<!-- \/wp:paragraph -->","_et_gb_content_width":"","footnotes":""},"categories":[2066,11],"tags":[85,419,574,2077,2199,2200],"class_list":["post-14873","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-categoria-actualitat","category-fefac","tag-fefac","tag-arco","tag-venda-per-internet","tag-venda-a-distancia","tag-roger-canals","tag-entregoo"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Dubtes sobre la legalitat d&#039;Entregoo, una app d&#039;enviament de medicaments<\/title>\n<meta name=\"description\" content=\"Roger Canals, advocat de la FEFAC, parla a Correo Farmac\u00e9utico de la venda a dist\u00e0ncia de medicaments i la legalitat del servei d&#039;Entregoo.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/fefac.cat\/empresarial\/dubtes-sobre-legalitat-entregoo-roger-canals-arco-rp\/\" \/>\n<meta property=\"og:locale\" content=\"ca_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Dubtes sobre la legalitat d&#039;Entregoo, una app d&#039;enviament de medicaments\" \/>\n<meta property=\"og:description\" content=\"Roger Canals, advocat de la FEFAC, parla a Correo Farmac\u00e9utico de la venda a dist\u00e0ncia de medicaments i la legalitat del servei d&#039;Entregoo.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/fefac.cat\/empresarial\/dubtes-sobre-legalitat-entregoo-roger-canals-arco-rp\/\" \/>\n<meta property=\"og:site_name\" content=\"FEFAC\" \/>\n<meta property=\"article:published_time\" content=\"2019-07-15T08:38:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-07-15T08:40:50+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/fefac.cat\/empresarial\/wp-content\/uploads\/2019\/07\/entregoo.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1152\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"lclavijo@afb.cat\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrit per\" \/>\n\t<meta name=\"twitter:data1\" content=\"lclavijo@afb.cat\" \/>\n\t<meta name=\"twitter:label2\" content=\"Temps estimat de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minut\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/fefac.cat\\\/empresarial\\\/dubtes-sobre-legalitat-entregoo-roger-canals-arco-rp\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fefac.cat\\\/empresarial\\\/dubtes-sobre-legalitat-entregoo-roger-canals-arco-rp\\\/\"},\"author\":{\"name\":\"lclavijo@afb.cat\",\"@id\":\"https:\\\/\\\/fefac.cat\\\/empresarial\\\/#\\\/schema\\\/person\\\/6ac15c94fb359972b6bfa9c752486744\"},\"headline\":\"Dubtes sobre la legalitat d&#8217;Entregoo, una altra aplicaci\u00f3 d&#8217;enviament de medicaments.\",\"datePublished\":\"2019-07-15T08:38:00+00:00\",\"dateModified\":\"2019-07-15T08:40:50+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/fefac.cat\\\/empresarial\\\/dubtes-sobre-legalitat-entregoo-roger-canals-arco-rp\\\/\"},\"wordCount\":283,\"image\":{\"@id\":\"https:\\\/\\\/fefac.cat\\\/empresarial\\\/dubtes-sobre-legalitat-entregoo-roger-canals-arco-rp\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/fefac.cat\\\/empresarial\\\/wp-content\\\/uploads\\\/2019\\\/07\\\/entregoo.jpg\",\"keywords\":[\"FEFAC\",\"ARCO\",\"venda per internet\",\"venda a dist\u00e0ncia\",\"Roger Canals\",\"Entregoo\"],\"articleSection\":[\"Actualitat\",\"FEFAC\"],\"inLanguage\":\"ca\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/fefac.cat\\\/empresarial\\\/dubtes-sobre-legalitat-entregoo-roger-canals-arco-rp\\\/\",\"url\":\"https:\\\/\\\/fefac.cat\\\/empresarial\\\/dubtes-sobre-legalitat-entregoo-roger-canals-arco-rp\\\/\",\"name\":\"Dubtes sobre la legalitat d'Entregoo, una app d'enviament de medicaments\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fefac.cat\\\/empresarial\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/fefac.cat\\\/empresarial\\\/dubtes-sobre-legalitat-entregoo-roger-canals-arco-rp\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/fefac.cat\\\/empresarial\\\/dubtes-sobre-legalitat-entregoo-roger-canals-arco-rp\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/fefac.cat\\\/empresarial\\\/wp-content\\\/uploads\\\/2019\\\/07\\\/entregoo.jpg\",\"datePublished\":\"2019-07-15T08:38:00+00:00\",\"dateModified\":\"2019-07-15T08:40:50+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/fefac.cat\\\/empresarial\\\/#\\\/schema\\\/person\\\/6ac15c94fb359972b6bfa9c752486744\"},\"description\":\"Roger Canals, advocat de la FEFAC, parla a Correo Farmac\u00e9utico de la venda a dist\u00e0ncia de medicaments i la legalitat del servei d'Entregoo.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/fefac.cat\\\/empresarial\\\/dubtes-sobre-legalitat-entregoo-roger-canals-arco-rp\\\/#breadcrumb\"},\"inLanguage\":\"ca\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/fefac.cat\\\/empresarial\\\/dubtes-sobre-legalitat-entregoo-roger-canals-arco-rp\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/fefac.cat\\\/empresarial\\\/dubtes-sobre-legalitat-entregoo-roger-canals-arco-rp\\\/#primaryimage\",\"url\":\"https:\\\/\\\/fefac.cat\\\/empresarial\\\/wp-content\\\/uploads\\\/2019\\\/07\\\/entregoo.jpg\",\"contentUrl\":\"https:\\\/\\\/fefac.cat\\\/empresarial\\\/wp-content\\\/uploads\\\/2019\\\/07\\\/entregoo.jpg\",\"width\":1152,\"height\":720},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/fefac.cat\\\/empresarial\\\/dubtes-sobre-legalitat-entregoo-roger-canals-arco-rp\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/fefac.cat\\\/empresarial\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Dubtes sobre la legalitat d&#8217;Entregoo, una altra aplicaci\u00f3 d&#8217;enviament de medicaments.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/fefac.cat\\\/empresarial\\\/#website\",\"url\":\"https:\\\/\\\/fefac.cat\\\/empresarial\\\/\",\"name\":\"FEFAC\",\"description\":\"Federaci\u00f3 d&#039;Associacions de Farm\u00e0cies de Catalunya\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/fefac.cat\\\/empresarial\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ca\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/fefac.cat\\\/empresarial\\\/#\\\/schema\\\/person\\\/6ac15c94fb359972b6bfa9c752486744\",\"name\":\"lclavijo@afb.cat\",\"url\":\"https:\\\/\\\/fefac.cat\\\/empresarial\\\/author\\\/laura-2\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Dubtes sobre la legalitat d'Entregoo, una app d'enviament de medicaments","description":"Roger Canals, advocat de la FEFAC, parla a Correo Farmac\u00e9utico de la venda a dist\u00e0ncia de medicaments i la legalitat del servei d'Entregoo.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/fefac.cat\/empresarial\/dubtes-sobre-legalitat-entregoo-roger-canals-arco-rp\/","og_locale":"ca_ES","og_type":"article","og_title":"Dubtes sobre la legalitat d'Entregoo, una app d'enviament de medicaments","og_description":"Roger Canals, advocat de la FEFAC, parla a Correo Farmac\u00e9utico de la venda a dist\u00e0ncia de medicaments i la legalitat del servei d'Entregoo.","og_url":"https:\/\/fefac.cat\/empresarial\/dubtes-sobre-legalitat-entregoo-roger-canals-arco-rp\/","og_site_name":"FEFAC","article_published_time":"2019-07-15T08:38:00+00:00","article_modified_time":"2019-07-15T08:40:50+00:00","og_image":[{"width":1152,"height":720,"url":"https:\/\/fefac.cat\/empresarial\/wp-content\/uploads\/2019\/07\/entregoo.jpg","type":"image\/jpeg"}],"author":"lclavijo@afb.cat","twitter_card":"summary_large_image","twitter_misc":{"Escrit per":"lclavijo@afb.cat","Temps estimat de lectura":"1 minut"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/fefac.cat\/empresarial\/dubtes-sobre-legalitat-entregoo-roger-canals-arco-rp\/#article","isPartOf":{"@id":"https:\/\/fefac.cat\/empresarial\/dubtes-sobre-legalitat-entregoo-roger-canals-arco-rp\/"},"author":{"name":"lclavijo@afb.cat","@id":"https:\/\/fefac.cat\/empresarial\/#\/schema\/person\/6ac15c94fb359972b6bfa9c752486744"},"headline":"Dubtes sobre la legalitat d&#8217;Entregoo, una altra aplicaci\u00f3 d&#8217;enviament de medicaments.","datePublished":"2019-07-15T08:38:00+00:00","dateModified":"2019-07-15T08:40:50+00:00","mainEntityOfPage":{"@id":"https:\/\/fefac.cat\/empresarial\/dubtes-sobre-legalitat-entregoo-roger-canals-arco-rp\/"},"wordCount":283,"image":{"@id":"https:\/\/fefac.cat\/empresarial\/dubtes-sobre-legalitat-entregoo-roger-canals-arco-rp\/#primaryimage"},"thumbnailUrl":"https:\/\/fefac.cat\/empresarial\/wp-content\/uploads\/2019\/07\/entregoo.jpg","keywords":["FEFAC","ARCO","venda per internet","venda a dist\u00e0ncia","Roger Canals","Entregoo"],"articleSection":["Actualitat","FEFAC"],"inLanguage":"ca"},{"@type":"WebPage","@id":"https:\/\/fefac.cat\/empresarial\/dubtes-sobre-legalitat-entregoo-roger-canals-arco-rp\/","url":"https:\/\/fefac.cat\/empresarial\/dubtes-sobre-legalitat-entregoo-roger-canals-arco-rp\/","name":"Dubtes sobre la legalitat d'Entregoo, una app d'enviament de medicaments","isPartOf":{"@id":"https:\/\/fefac.cat\/empresarial\/#website"},"primaryImageOfPage":{"@id":"https:\/\/fefac.cat\/empresarial\/dubtes-sobre-legalitat-entregoo-roger-canals-arco-rp\/#primaryimage"},"image":{"@id":"https:\/\/fefac.cat\/empresarial\/dubtes-sobre-legalitat-entregoo-roger-canals-arco-rp\/#primaryimage"},"thumbnailUrl":"https:\/\/fefac.cat\/empresarial\/wp-content\/uploads\/2019\/07\/entregoo.jpg","datePublished":"2019-07-15T08:38:00+00:00","dateModified":"2019-07-15T08:40:50+00:00","author":{"@id":"https:\/\/fefac.cat\/empresarial\/#\/schema\/person\/6ac15c94fb359972b6bfa9c752486744"},"description":"Roger Canals, advocat de la FEFAC, parla a Correo Farmac\u00e9utico de la venda a dist\u00e0ncia de medicaments i la legalitat del servei d'Entregoo.","breadcrumb":{"@id":"https:\/\/fefac.cat\/empresarial\/dubtes-sobre-legalitat-entregoo-roger-canals-arco-rp\/#breadcrumb"},"inLanguage":"ca","potentialAction":[{"@type":"ReadAction","target":["https:\/\/fefac.cat\/empresarial\/dubtes-sobre-legalitat-entregoo-roger-canals-arco-rp\/"]}]},{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/fefac.cat\/empresarial\/dubtes-sobre-legalitat-entregoo-roger-canals-arco-rp\/#primaryimage","url":"https:\/\/fefac.cat\/empresarial\/wp-content\/uploads\/2019\/07\/entregoo.jpg","contentUrl":"https:\/\/fefac.cat\/empresarial\/wp-content\/uploads\/2019\/07\/entregoo.jpg","width":1152,"height":720},{"@type":"BreadcrumbList","@id":"https:\/\/fefac.cat\/empresarial\/dubtes-sobre-legalitat-entregoo-roger-canals-arco-rp\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/fefac.cat\/empresarial\/"},{"@type":"ListItem","position":2,"name":"Dubtes sobre la legalitat d&#8217;Entregoo, una altra aplicaci\u00f3 d&#8217;enviament de medicaments."}]},{"@type":"WebSite","@id":"https:\/\/fefac.cat\/empresarial\/#website","url":"https:\/\/fefac.cat\/empresarial\/","name":"FEFAC","description":"Federaci\u00f3 d&#039;Associacions de Farm\u00e0cies de Catalunya","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/fefac.cat\/empresarial\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ca"},{"@type":"Person","@id":"https:\/\/fefac.cat\/empresarial\/#\/schema\/person\/6ac15c94fb359972b6bfa9c752486744","name":"lclavijo@afb.cat","url":"https:\/\/fefac.cat\/empresarial\/author\/laura-2\/"}]}},"_links":{"self":[{"href":"https:\/\/fefac.cat\/empresarial\/wp-json\/wp\/v2\/posts\/14873","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fefac.cat\/empresarial\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fefac.cat\/empresarial\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fefac.cat\/empresarial\/wp-json\/wp\/v2\/users\/2313"}],"replies":[{"embeddable":true,"href":"https:\/\/fefac.cat\/empresarial\/wp-json\/wp\/v2\/comments?post=14873"}],"version-history":[{"count":0,"href":"https:\/\/fefac.cat\/empresarial\/wp-json\/wp\/v2\/posts\/14873\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fefac.cat\/empresarial\/wp-json\/wp\/v2\/media\/14876"}],"wp:attachment":[{"href":"https:\/\/fefac.cat\/empresarial\/wp-json\/wp\/v2\/media?parent=14873"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fefac.cat\/empresarial\/wp-json\/wp\/v2\/categories?post=14873"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fefac.cat\/empresarial\/wp-json\/wp\/v2\/tags?post=14873"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}