{"id":7201,"date":"2017-03-16T16:12:43","date_gmt":"2017-03-16T16:12:43","guid":{"rendered":"http:\/\/fefac.cat\/empresarial\/?p=7201"},"modified":"2017-03-16T16:12:43","modified_gmt":"2017-03-16T16:12:43","slug":"las-farmacias-de-baleares-empiezan-a-sumarse-a-la","status":"publish","type":"post","link":"https:\/\/fefac.cat\/empresarial\/las-farmacias-de-baleares-empiezan-a-sumarse-a-la\/","title":{"rendered":"Las farmacias de Baleares empiezan a sumarse a la Campa\u00f1a \u2018Frena el sol, frena el lupus\u2019"},"content":{"rendered":"<ul>\n<li><strong>La iniciativa promueve el uso de los fotoprotectores solares en pacientes con lupus, puesto que para ellos es fundamental protegerse de los rayos solares.<\/strong><\/li>\n<li><strong>Est&aacute; previsto que la Campa&ntilde;a, implantada de momento en 190 farmacias catalanas y 53 aragonesas, se extienda a otras comunidades aut&oacute;nomas.<\/strong><\/li>\n<\/ul>\n<p><strong>Barcelona, 16 de marzo de 2016. <\/strong>Farmacias de Baleares han comenzado a sumarse a la Campa&ntilde;a &lsquo;<em>Frena el sol, frena el lupus<\/em>&rsquo;, impulsada por la Federaci&oacute;n de Asociaciones de Farmacias de Catalu&ntilde;a (FEFAC), que ha sido presentada hoy en la sede del Colegio de Farmac&eacute;uticos de Islas Baleares (COFIB), con la asistencia de una cincuentena de personas, entre pacientes y farmac&eacute;uticos. El COFIB, junto a la Asociaci&oacute;n de Lupus de Baleares (Aiblupus), las distribuidoras Cooperativa Apotecaris, Alliance Healthcare y Cofarme, y el laboratorio Ferrer, han hecho posible que la iniciativa, que ya se lleva a cabo en Catalu&ntilde;a y Arag&oacute;n, se implante en Baleares.<\/p>\n<p>La campa&ntilde;a tiene como objetivo facilitar a los pacientes de lupus el acceso, a trav&eacute;s de las farmacias participantes, a fotoprotectores de calidad a la mitad de su precio, pues la aplicaci&oacute;n de estos productos es fundamental para evitar el agravamiento del lupus.<\/p>\n<p>La campa&ntilde;a fue puesta en marcha por FEFAC en Catalu&ntilde;a en el a&ntilde;o 2015, con la colaboraci&oacute;n de Ferrer, la Asociaci&oacute;n Catalana de Lupus Eritematoso (ACLEG), y las distribuidoras Alliance Healthcare y Fedefarma. El pasado a&ntilde;o, se extendi&oacute; a Arag&oacute;n, sumando a los colegios de farmac&eacute;uticos aragoneses, la Asociaci&oacute;n de lupus de Arag&oacute;n (Alada), el apoyo de la distribuci&oacute;n Novaltia y la empresarial de farmacias de Zaragoza. Las farmacias participantes en Catalu&ntilde;a son 190, mientras que en Arag&oacute;n se han sumado de momento 53, y se est&aacute; trabajando para implantarla pr&oacute;ximamente en otras provincias y comunidades aut&oacute;nomas.<\/p>\n<p>Benito Pr&oacute;sper, director general de Planificaci&oacute;n, Evaluaci&oacute;n y Farmacia de Islas Baleares, ha comentado que abordar la cronicidad es uno de los principales retos de la Consejer&iacute;a de Sanidad, y que en el nuevo plan de atenci&oacute;n a los pacientes con patolog&iacute;as cr&oacute;nicas cuenta con la farmacia comunitaria como un agente de salud m&aacute;s. &ldquo;En enfermedades cr&oacute;nicas como el lupus, que requieren de diferentes medicamentos, el papel de las farmacias es muy importante, y desde la Consejer&iacute;a apoyaremos iniciativas como &eacute;sta&rdquo;, ha subrayado.<\/p>\n<p>Antonio Torres, presidente de FEFAC, ha se&ntilde;alado que &quot;<em style=\"font-size: 13px;\">Frena el sol, frena el lupus,<\/em><span style=\"font-size: 13px;\"> aparte de fomentar una medida de prevenci&oacute;n para evitar un desencadenante del lupus como son los rayos UV del sol, contribuye a reforzar el papel del farmac&eacute;utico en el consejo a estos pacientes sobre protecci&oacute;n solar, otros aspectos de su salud y el uso de los medicamentos&rdquo;.<\/span><\/p>\n<p>Por su parte, la presidenta de Aiblupus y de la Federaci&oacute;n Espa&ntilde;ola de Lupus (Felupus), Mar&iacute;a Jos&eacute; Lebrero, afirma: &ldquo;Las farmacias tienen un gran papel en esta campa&ntilde;a, puesto que nos facilitan el acceso a las cremas solares, un hecho importante, pues nosotros utilizamos todos los d&iacute;as estos productos, pero no como un cosm&eacute;tico, sino como un tratamiento necesario&rdquo;.<\/p>\n<p>&ldquo;La campa&ntilde;a nos parece una magn&iacute;fica iniciativa y los farmac&eacute;uticos de baleares, como profesionales sanitarios de primer orden, consideramos que debemos aportar todo lo posible a las actividades que puedan redundar en beneficio de los pacientes, y m&aacute;s a&uacute;n si son pacientes cr&oacute;nicos cuyo d&iacute;a a d&iacute;a puede ser muy duro&rdquo;, apunta Antoni Real, presidente del Colegio de Farmac&eacute;uticos de Islas Baleares. &ldquo;El conjunto del sector se une en favor de un colectivo de pacientes que necesita de este tipo de iniciativas, lo que es todo un ejemplo dentro de nuestro sector. Esta l&iacute;nea de colaboraci&oacute;n deber&iacute;a realizarse con m&aacute;s regularidad&rdquo;, a&ntilde;ade.<\/p>\n<p>C&eacute;sar Mart&iacute;nez, presidente no ejecutivo de Alliance Healthcare, explica que la responsabilidad social corporativa forma parte integral del negocio de esta distribuidora: &ldquo;Es inherente a nuestros valores y forma parte natural de nuestra filosof&iacute;a. Adem&aacute;s, como compa&ntilde;&iacute;a dedicada al cuidado de la salud, sentimos un gran orgullo de poder jugar un papel activo en la lucha contra el lupus, una enfermedad que afecta a unas 40.000 personas en nuestro pa&iacute;s&rdquo;, se&ntilde;ala.<\/p>\n<p>Desde Cooperativa d&rsquo;Apotecaris, su presidente, Eladio Gonz&aacute;lez, afirma: &ldquo;La implicaci&oacute;n de nuestra entidad en todas aquellas iniciativas que tienen como objetivo potenciar la salud de las personas y mejorar su calidad de vida ha sido, tradicionalmente, una se&ntilde;a de identidad de la Cooperativa d&rsquo;Apotecaris, y en este caso con mayor raz&oacute;n a&uacute;n, desde el momento que la citada campa&ntilde;a surge desde el propio seno del sector farmac&eacute;utico en su conjunto&rdquo;.<\/p>\n<p>Por su parte, Javier Garc&iacute;a Veiga, en representaci&oacute;n de Cofarme, tambi&eacute;n destaca &lsquo;<em>Frena el sol, frena el lupu<\/em>s&rsquo;, como iniciativa que &ldquo;ha conseguido implicar a la industria farmac&eacute;utica, la distribuci&oacute;n, la empresarial de farmacias, el Colegio de Farmac&eacute;uticos, es decir, involucrar a todo el colectivo farmac&eacute;utico en una campa&ntilde;a de promoci&oacute;n de la salud y prevenci&oacute;n de la enfermedad&rdquo;.<\/p>\n<p><strong>El lupus<\/strong><\/p>\n<p>El Lupus Eritematoso Sist&eacute;mico (LES) es una enfermedad autoinmune producida por los propios anticuerpos que atacan a las c&eacute;lulas del organismo. Afecta a unas 45.000 personas en Espa&ntilde;a y se manifiesta entre los 15 y los 40 a&ntilde;os, siendo m&aacute;s frecuente entre las mujeres (con una relaci&oacute;n de 9 a 1).<\/p>\n<p>Se produce en brotes que pueden provocar, entre otros s&iacute;ntomas, alternaciones en la piel, dolores musculares, p&eacute;rdida de peso, fiebre o cansancio. Dichos s&iacute;ntomas pueden presentarse de forma grave o leve, en intensidad y duraci&oacute;n. Las afectaciones m&aacute;s frecuentes son las renales, card&iacute;acas, pulmonares, articulares, neurol&oacute;gicas y cut&aacute;neas.<\/p>\n<p>Una de las causas que m&aacute;s hace empeorar la patolog&iacute;a son los rayos del sol (UV-B). La exposici&oacute;n solar no solo puede dar lugar a un brote cut&aacute;neo de la enfermedad, sino que tambi&eacute;n puede provocar un aumento importante de la actividad inflamatoria en forma de afectaci&oacute;n a cualquier &oacute;rgano. Por este motivo, es fundamental que los pacientes se protejan del sol, en cualquier estaci&oacute;n del a&ntilde;o. La campa&ntilde;a &lsquo;<em>frena el sol, frena el lupus<\/em>&rsquo; nace desde las farmacias con la voluntad de ayudar a los pacientes de esta enfermedad, a acceder a fotoprotectores de calidad, fundamentales para evitar el empeoramiento de la enfermedad.<\/p>\n<p><img decoding=\"async\" alt=\"\" data-src=\"http:\/\/www.fefac.cat\/intranet\/noticies\/_userfiles\/images\/Frena%20el%20sol%20frena%20el%20lupus%20Baleares%20para%20web.jpg\" style=\"width: 450px; height: 300px;\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" \/><\/p>\n<p><img decoding=\"async\" alt=\"\" data-src=\"http:\/\/www.fefac.cat\/intranet\/noticies\/_userfiles\/images\/lupus%20balears%20per%20a%20web.jpg\" style=\"width: 450px; height: 213px;\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" \/><\/p>\n<p><img decoding=\"async\" alt=\"\" data-src=\"http:\/\/www.fefac.cat\/intranet\/noticies\/_userfiles\/images\/lupus%20balears%20web.jpg\" style=\"width: 450px; height: 242px;\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La iniciativa promueve el uso de los fotoprotectores solares en pacientes con lupus, puesto que para ellos es fundamental protegerse de los rayos solares. Est&aacute; previsto que la Campa&ntilde;a, implantada [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[2067,11,12,13,14,15],"tags":[434,480,578,620,1240,1323,1515,1516,1523],"class_list":["post-7201","post","type-post","status-publish","format-standard","hentry","category-notes-premsa","category-fefac","category-afb","category-afet","category-afell","category-agfe","tag-lupus","tag-ferrer","tag-fedefarma","tag-alliance-healthcare","tag-acleg","tag-frenasol","tag-balears","tag-apotecaris","tag-cofarme"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Las farmacias de Baleares empiezan a sumarse a la Campa\u00f1a \u2018Frena el sol, frena el lupus\u2019 - FEFAC<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/fefac.cat\/empresarial\/las-farmacias-de-baleares-empiezan-a-sumarse-a-la\/\" \/>\n<meta property=\"og:locale\" content=\"ca_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Las farmacias de Baleares empiezan a sumarse a la Campa\u00f1a \u2018Frena el sol, frena el lupus\u2019 - FEFAC\" \/>\n<meta property=\"og:description\" content=\"La iniciativa promueve el uso de los fotoprotectores solares en pacientes con lupus, puesto que para ellos es fundamental protegerse de los rayos solares. Est&aacute; previsto que la Campa&ntilde;a, implantada [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/fefac.cat\/empresarial\/las-farmacias-de-baleares-empiezan-a-sumarse-a-la\/\" \/>\n<meta property=\"og:site_name\" content=\"FEFAC\" \/>\n<meta property=\"article:published_time\" content=\"2017-03-16T16:12:43+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/www.fefac.cat\/intranet\/noticies\/_userfiles\/images\/Frena%20el%20sol%20frena%20el%20lupus%20Baleares%20para%20web.jpg\" \/>\n<meta name=\"author\" content=\"qabh859\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrit per\" \/>\n\t<meta name=\"twitter:data1\" content=\"qabh859\" \/>\n\t<meta name=\"twitter:label2\" content=\"Temps estimat de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minuts\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/fefac.cat\\\/empresarial\\\/las-farmacias-de-baleares-empiezan-a-sumarse-a-la\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fefac.cat\\\/empresarial\\\/las-farmacias-de-baleares-empiezan-a-sumarse-a-la\\\/\"},\"author\":{\"name\":\"qabh859\",\"@id\":\"https:\\\/\\\/fefac.cat\\\/empresarial\\\/#\\\/schema\\\/person\\\/03012b2506772bd65738ce781a3947f7\"},\"headline\":\"Las farmacias de Baleares empiezan a sumarse a la Campa\u00f1a \u2018Frena el sol, frena el lupus\u2019\",\"datePublished\":\"2017-03-16T16:12:43+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/fefac.cat\\\/empresarial\\\/las-farmacias-de-baleares-empiezan-a-sumarse-a-la\\\/\"},\"wordCount\":1254,\"image\":{\"@id\":\"https:\\\/\\\/fefac.cat\\\/empresarial\\\/las-farmacias-de-baleares-empiezan-a-sumarse-a-la\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.fefac.cat\\\/intranet\\\/noticies\\\/_userfiles\\\/images\\\/Frena%20el%20sol%20frena%20el%20lupus%20Baleares%20para%20web.jpg\",\"keywords\":[\"lupus\",\"Ferrer\",\"Fedefarma\",\"Alliance Healthcare\",\"ACLEG\",\"frenasol\",\"Balears\",\"Apotecaris\",\"Cofarme\"],\"articleSection\":[\"Notes de premsa\",\"FEFAC\",\"AFB\",\"AFET\",\"AFELL\",\"AGFE\"],\"inLanguage\":\"ca\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/fefac.cat\\\/empresarial\\\/las-farmacias-de-baleares-empiezan-a-sumarse-a-la\\\/\",\"url\":\"https:\\\/\\\/fefac.cat\\\/empresarial\\\/las-farmacias-de-baleares-empiezan-a-sumarse-a-la\\\/\",\"name\":\"Las farmacias de Baleares empiezan a sumarse a la Campa\u00f1a \u2018Frena el sol, frena el lupus\u2019 - FEFAC\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fefac.cat\\\/empresarial\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/fefac.cat\\\/empresarial\\\/las-farmacias-de-baleares-empiezan-a-sumarse-a-la\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/fefac.cat\\\/empresarial\\\/las-farmacias-de-baleares-empiezan-a-sumarse-a-la\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.fefac.cat\\\/intranet\\\/noticies\\\/_userfiles\\\/images\\\/Frena%20el%20sol%20frena%20el%20lupus%20Baleares%20para%20web.jpg\",\"datePublished\":\"2017-03-16T16:12:43+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/fefac.cat\\\/empresarial\\\/#\\\/schema\\\/person\\\/03012b2506772bd65738ce781a3947f7\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/fefac.cat\\\/empresarial\\\/las-farmacias-de-baleares-empiezan-a-sumarse-a-la\\\/#breadcrumb\"},\"inLanguage\":\"ca\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/fefac.cat\\\/empresarial\\\/las-farmacias-de-baleares-empiezan-a-sumarse-a-la\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/fefac.cat\\\/empresarial\\\/las-farmacias-de-baleares-empiezan-a-sumarse-a-la\\\/#primaryimage\",\"url\":\"http:\\\/\\\/www.fefac.cat\\\/intranet\\\/noticies\\\/_userfiles\\\/images\\\/Frena%20el%20sol%20frena%20el%20lupus%20Baleares%20para%20web.jpg\",\"contentUrl\":\"http:\\\/\\\/www.fefac.cat\\\/intranet\\\/noticies\\\/_userfiles\\\/images\\\/Frena%20el%20sol%20frena%20el%20lupus%20Baleares%20para%20web.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/fefac.cat\\\/empresarial\\\/las-farmacias-de-baleares-empiezan-a-sumarse-a-la\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/fefac.cat\\\/empresarial\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Las farmacias de Baleares empiezan a sumarse a la Campa\u00f1a \u2018Frena el sol, frena el lupus\u2019\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/fefac.cat\\\/empresarial\\\/#website\",\"url\":\"https:\\\/\\\/fefac.cat\\\/empresarial\\\/\",\"name\":\"FEFAC\",\"description\":\"Federaci\u00f3 d&#039;Associacions de Farm\u00e0cies de Catalunya\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/fefac.cat\\\/empresarial\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ca\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/fefac.cat\\\/empresarial\\\/#\\\/schema\\\/person\\\/03012b2506772bd65738ce781a3947f7\",\"name\":\"qabh859\",\"url\":\"https:\\\/\\\/fefac.cat\\\/empresarial\\\/author\\\/qabh859\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Las farmacias de Baleares empiezan a sumarse a la Campa\u00f1a \u2018Frena el sol, frena el lupus\u2019 - FEFAC","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/fefac.cat\/empresarial\/las-farmacias-de-baleares-empiezan-a-sumarse-a-la\/","og_locale":"ca_ES","og_type":"article","og_title":"Las farmacias de Baleares empiezan a sumarse a la Campa\u00f1a \u2018Frena el sol, frena el lupus\u2019 - FEFAC","og_description":"La iniciativa promueve el uso de los fotoprotectores solares en pacientes con lupus, puesto que para ellos es fundamental protegerse de los rayos solares. Est&aacute; previsto que la Campa&ntilde;a, implantada [&hellip;]","og_url":"https:\/\/fefac.cat\/empresarial\/las-farmacias-de-baleares-empiezan-a-sumarse-a-la\/","og_site_name":"FEFAC","article_published_time":"2017-03-16T16:12:43+00:00","og_image":[{"url":"http:\/\/www.fefac.cat\/intranet\/noticies\/_userfiles\/images\/Frena%20el%20sol%20frena%20el%20lupus%20Baleares%20para%20web.jpg","type":"","width":"","height":""}],"author":"qabh859","twitter_card":"summary_large_image","twitter_misc":{"Escrit per":"qabh859","Temps estimat de lectura":"6 minuts"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/fefac.cat\/empresarial\/las-farmacias-de-baleares-empiezan-a-sumarse-a-la\/#article","isPartOf":{"@id":"https:\/\/fefac.cat\/empresarial\/las-farmacias-de-baleares-empiezan-a-sumarse-a-la\/"},"author":{"name":"qabh859","@id":"https:\/\/fefac.cat\/empresarial\/#\/schema\/person\/03012b2506772bd65738ce781a3947f7"},"headline":"Las farmacias de Baleares empiezan a sumarse a la Campa\u00f1a \u2018Frena el sol, frena el lupus\u2019","datePublished":"2017-03-16T16:12:43+00:00","mainEntityOfPage":{"@id":"https:\/\/fefac.cat\/empresarial\/las-farmacias-de-baleares-empiezan-a-sumarse-a-la\/"},"wordCount":1254,"image":{"@id":"https:\/\/fefac.cat\/empresarial\/las-farmacias-de-baleares-empiezan-a-sumarse-a-la\/#primaryimage"},"thumbnailUrl":"http:\/\/www.fefac.cat\/intranet\/noticies\/_userfiles\/images\/Frena%20el%20sol%20frena%20el%20lupus%20Baleares%20para%20web.jpg","keywords":["lupus","Ferrer","Fedefarma","Alliance Healthcare","ACLEG","frenasol","Balears","Apotecaris","Cofarme"],"articleSection":["Notes de premsa","FEFAC","AFB","AFET","AFELL","AGFE"],"inLanguage":"ca"},{"@type":"WebPage","@id":"https:\/\/fefac.cat\/empresarial\/las-farmacias-de-baleares-empiezan-a-sumarse-a-la\/","url":"https:\/\/fefac.cat\/empresarial\/las-farmacias-de-baleares-empiezan-a-sumarse-a-la\/","name":"Las farmacias de Baleares empiezan a sumarse a la Campa\u00f1a \u2018Frena el sol, frena el lupus\u2019 - FEFAC","isPartOf":{"@id":"https:\/\/fefac.cat\/empresarial\/#website"},"primaryImageOfPage":{"@id":"https:\/\/fefac.cat\/empresarial\/las-farmacias-de-baleares-empiezan-a-sumarse-a-la\/#primaryimage"},"image":{"@id":"https:\/\/fefac.cat\/empresarial\/las-farmacias-de-baleares-empiezan-a-sumarse-a-la\/#primaryimage"},"thumbnailUrl":"http:\/\/www.fefac.cat\/intranet\/noticies\/_userfiles\/images\/Frena%20el%20sol%20frena%20el%20lupus%20Baleares%20para%20web.jpg","datePublished":"2017-03-16T16:12:43+00:00","author":{"@id":"https:\/\/fefac.cat\/empresarial\/#\/schema\/person\/03012b2506772bd65738ce781a3947f7"},"breadcrumb":{"@id":"https:\/\/fefac.cat\/empresarial\/las-farmacias-de-baleares-empiezan-a-sumarse-a-la\/#breadcrumb"},"inLanguage":"ca","potentialAction":[{"@type":"ReadAction","target":["https:\/\/fefac.cat\/empresarial\/las-farmacias-de-baleares-empiezan-a-sumarse-a-la\/"]}]},{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/fefac.cat\/empresarial\/las-farmacias-de-baleares-empiezan-a-sumarse-a-la\/#primaryimage","url":"http:\/\/www.fefac.cat\/intranet\/noticies\/_userfiles\/images\/Frena%20el%20sol%20frena%20el%20lupus%20Baleares%20para%20web.jpg","contentUrl":"http:\/\/www.fefac.cat\/intranet\/noticies\/_userfiles\/images\/Frena%20el%20sol%20frena%20el%20lupus%20Baleares%20para%20web.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/fefac.cat\/empresarial\/las-farmacias-de-baleares-empiezan-a-sumarse-a-la\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/fefac.cat\/empresarial\/"},{"@type":"ListItem","position":2,"name":"Las farmacias de Baleares empiezan a sumarse a la Campa\u00f1a \u2018Frena el sol, frena el lupus\u2019"}]},{"@type":"WebSite","@id":"https:\/\/fefac.cat\/empresarial\/#website","url":"https:\/\/fefac.cat\/empresarial\/","name":"FEFAC","description":"Federaci\u00f3 d&#039;Associacions de Farm\u00e0cies de Catalunya","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/fefac.cat\/empresarial\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ca"},{"@type":"Person","@id":"https:\/\/fefac.cat\/empresarial\/#\/schema\/person\/03012b2506772bd65738ce781a3947f7","name":"qabh859","url":"https:\/\/fefac.cat\/empresarial\/author\/qabh859\/"}]}},"_links":{"self":[{"href":"https:\/\/fefac.cat\/empresarial\/wp-json\/wp\/v2\/posts\/7201","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fefac.cat\/empresarial\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fefac.cat\/empresarial\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fefac.cat\/empresarial\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/fefac.cat\/empresarial\/wp-json\/wp\/v2\/comments?post=7201"}],"version-history":[{"count":0,"href":"https:\/\/fefac.cat\/empresarial\/wp-json\/wp\/v2\/posts\/7201\/revisions"}],"wp:attachment":[{"href":"https:\/\/fefac.cat\/empresarial\/wp-json\/wp\/v2\/media?parent=7201"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fefac.cat\/empresarial\/wp-json\/wp\/v2\/categories?post=7201"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fefac.cat\/empresarial\/wp-json\/wp\/v2\/tags?post=7201"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}