{"id":8547,"date":"2017-09-12T13:42:59","date_gmt":"2017-09-12T13:42:59","guid":{"rendered":"http:\/\/fefac.cat\/empresarial\/?p=8547"},"modified":"2017-09-12T13:42:59","modified_gmt":"2017-09-12T13:42:59","slug":"barcelona-s-una-candidatura-imbatible-com-a-seu","status":"publish","type":"post","link":"https:\/\/fefac.cat\/empresarial\/barcelona-s-una-candidatura-imbatible-com-a-seu\/","title":{"rendered":"Barcelona \u00e9s una candidatura \u201cimbatible\u201d com a seu de l\u2019Ag\u00e8ncia Europea del Medicament"},"content":{"rendered":"<p>El conseller de Salut, Antoni Com&iacute;n, entrevistat recentment al programa <a href=\"http:\/\/www.ccma.cat\/tv3\/alacarta\/programa\/toni-comin-la-capacitat-de-resposta-del-sem-va-ser-superior-a-la-dels-atemptats-de-londres\/video\/5684911\/\">Els Matins de TV3<\/a>, opina&nbsp;que la decisi&oacute; sobre la ciutat que albergar&agrave; la seu de l&rsquo;Ag&egrave;ncia Europea del Medicament, que correspon al Consell europeu, &eacute;s d&rsquo;una gran complexitat.<\/p>\n<p>No obstant aix&ograve;, est&agrave; conven&ccedil;ut que el Govern de la Generalitat, en col&middot;laboraci&oacute; amb el de l&rsquo;Estat espanyol i l&rsquo;Ajuntament de Barcelona, han presentat la millor proposta. &ldquo;Des del punt de vista t&egrave;cnic, la candidatura de Barcelona &eacute;s imbatible&rdquo;, assegura a l&#39;entrevista. &ldquo;Si la decisi&oacute; &eacute;s molt t&egrave;cnica, la seu vindr&agrave; aqu&iacute;, i si a la decisi&oacute; es barregen altres consideracions no t&egrave;cniques, hi ha ciutats que s&oacute;n rivals dif&iacute;cils&rdquo;, assenyala.<\/p>\n<p>Preguntat sobre com poden influir els aspectes pol&iacute;tics en aquesta decisi&oacute;, Comin respon que, &ldquo;si la condici&oacute; &eacute;s que la ciutat on es trobi l&rsquo;EMA formi part de la Uni&oacute; Europea, nosaltres volem seguir dins la UE; per tant, no veig que hi hagi cap obstacle insalvable des d&rsquo;aquet punt de vista&rdquo;, afirma a l&rsquo;entrevista.<\/p>\n<p>Sobre les caracter&iacute;stiques de Barcelona per acollir la seu de l&rsquo;Ag&egrave;ncia, s&oacute;n enumerades per Jordi Ramentol, president de la Aesgp (associaci&oacute; europea de laboratoris per a l&rsquo;autocura de la salut) i videpresident de Farmaindustria, en una&nbsp;<a href=\"http:\/\/www.elperiodico.cat\/ca\/opinio\/20170829\/agencia-europea-de-medicaments-barcelona-salt-al-futur-6252625\">columna d&rsquo;opini&oacute;<\/a> a El Peri&oacute;dico de Catalunya.<\/p>\n<p>Segons opina, Barcelona com a seu &eacute;s &ldquo;la ciutat perfecta, la que millor pot garantir un canvi d&rsquo;ubicaci&oacute; de forma efica&ccedil; i sense traumes&rdquo;. Tal com explica, el seu panorama cient&iacute;fic &eacute;s molt destacat. &ldquo;Comptem amb 31 centres d&rsquo;investigaci&oacute; biom&egrave;dica, de ci&egrave;ncies de la salut i sanitat animal i amb 230 laboratoris que representen m&eacute;s del 50% de la ind&uacute;stria farmac&egrave;utica i veterin&agrave;ria espanyola. La nostra producci&oacute; farmac&egrave;utica i veterin&agrave;ria representa el 3,5% de la producci&oacute; europea del sector (comparable amb Dinamarca o Su&egrave;cia), i el sector farmac&egrave;utic catal&agrave; &eacute;s el cinqu&egrave; m&eacute;s productiu de la UE-15&rdquo;, afirma.<\/p>\n<p>A m&eacute;s, Espanya &eacute;s el segon pa&iacute;s europeu en nombre d&rsquo;assajos cl&iacute;nics realitzats, amb un creixement del 30% entre el 2005 i el 2016, i &eacute;s l&iacute;der mundial en assajos de medicaments de ter&agrave;pies avan&ccedil;ades. Tamb&eacute; assenyala a l&#39;entrevista&nbsp;com a element destacat que m&eacute;s del 40% de la despesa en investigaci&oacute; biom&egrave;dica a Espanya es porta a terme en col&middot;laboraci&oacute; amb el sector sanitari p&uacute;blic.<\/p>\n<p>Aix&iacute; mateix, indica que 190.000 universitaris que estudien aqu&iacute;, dels quals 32.000 ho fan en programes de m&agrave;ster o doctorat. A m&eacute;s, afirma que &ldquo;&eacute;s l&rsquo;&uacute;nica ciutat amb dues de les vuit millors escoles de negocis del m&oacute;n, Esade i IESE&rdquo;.<\/p>\n<p>La visi&oacute; de Ramentol sobre les conseq&uuml;&egrave;ncies de la possible ubicaci&oacute; de l&rsquo;EMA a Barcelona &eacute;s molt positiva: &ldquo;Aconseguir&iacute;em un gran impacte sobre el conjunt de la ind&uacute;stria; es crearia l&rsquo;efecte tractor que es traduiria en la instal&middot;laci&oacute; de companyies de diferents mides, i innombrables spin-&shy;offs i start-ups; creixerien nous centres d&rsquo;innovaci&oacute; i investigaci&oacute;; s&rsquo;atrauria el millor talent del m&oacute;n i moltes empreses de serveis de l&rsquo;&agrave;mbit de la salut; obtindr&iacute;em m&eacute;s ingressos per a assajos cl&iacute;nics&#8230;&rdquo;<\/p>\n<div style=\"background:#eee;border:1px solid #ccc;padding:5px 10px;\"><strong>Not&iacute;cies relacionades:<\/strong><\/div>\n<div style=\"background:#eee;border:1px solid #ccc;padding:5px 10px;\"><strong><a href=\"http:\/\/www.fefac.cat\/noticia.asp?id=5509\">Qu&egrave; diu la farm&agrave;cia catalana sobre la nova &Agrave;rea del Medicament?<\/a><\/strong><\/div>\n<div style=\"background:#eee;border:1px solid #ccc;padding:5px 10px;\"><strong><a href=\"http:\/\/www.fefac.cat\/noticia.asp?id=5447\">FEFAC fa pinya amb la societat civil i institucions perqu&egrave; Barcelona aculli la seu de l&rsquo;EMA<\/a><\/strong><\/div>\n<div style=\"background:#eee;border:1px solid #ccc;padding:5px 10px;\"><strong><a href=\"http:\/\/www.fefac.cat\/notapremsa.asp?id=5322\">FEFAC se suma al suport de la candidatura de Barcelona com a seu de l&rsquo;Ag&egrave;ncia Europea del Medicament<\/a><\/strong><\/div>\n","protected":false},"excerpt":{"rendered":"<p>El conseller de Salut, Antoni Com&iacute;n, entrevistat recentment al programa Els Matins de TV3, opina&nbsp;que la decisi&oacute; sobre la ciutat que albergar&agrave; la seu de l&rsquo;Ag&egrave;ncia Europea del Medicament, que [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[11,12,13,14,15,294],"tags":[759,943,1017],"class_list":["post-8547","post","type-post","status-publish","format-standard","hentry","category-fefac","category-afb","category-afet","category-afell","category-agfe","category-politica-sanitaria","tag-ema","tag-comin","tag-agencia-europea-medicaments"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Barcelona \u00e9s una candidatura \u201cimbatible\u201d com a seu de l\u2019Ag\u00e8ncia Europea del Medicament - FEFAC<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/fefac.cat\/empresarial\/barcelona-s-una-candidatura-imbatible-com-a-seu\/\" \/>\n<meta property=\"og:locale\" content=\"ca_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Barcelona \u00e9s una candidatura \u201cimbatible\u201d com a seu de l\u2019Ag\u00e8ncia Europea del Medicament - FEFAC\" \/>\n<meta property=\"og:description\" content=\"El conseller de Salut, Antoni Com&iacute;n, entrevistat recentment al programa Els Matins de TV3, opina&nbsp;que la decisi&oacute; sobre la ciutat que albergar&agrave; la seu de l&rsquo;Ag&egrave;ncia Europea del Medicament, que [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/fefac.cat\/empresarial\/barcelona-s-una-candidatura-imbatible-com-a-seu\/\" \/>\n<meta property=\"og:site_name\" content=\"FEFAC\" \/>\n<meta property=\"article:published_time\" content=\"2017-09-12T13:42:59+00:00\" \/>\n<meta name=\"author\" content=\"qabh859\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrit per\" \/>\n\t<meta name=\"twitter:data1\" content=\"qabh859\" \/>\n\t<meta name=\"twitter:label2\" content=\"Temps estimat de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minuts\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/fefac.cat\\\/empresarial\\\/barcelona-s-una-candidatura-imbatible-com-a-seu\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fefac.cat\\\/empresarial\\\/barcelona-s-una-candidatura-imbatible-com-a-seu\\\/\"},\"author\":{\"name\":\"qabh859\",\"@id\":\"https:\\\/\\\/fefac.cat\\\/empresarial\\\/#\\\/schema\\\/person\\\/03012b2506772bd65738ce781a3947f7\"},\"headline\":\"Barcelona \u00e9s una candidatura \u201cimbatible\u201d com a seu de l\u2019Ag\u00e8ncia Europea del Medicament\",\"datePublished\":\"2017-09-12T13:42:59+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/fefac.cat\\\/empresarial\\\/barcelona-s-una-candidatura-imbatible-com-a-seu\\\/\"},\"wordCount\":753,\"keywords\":[\"EMA\",\"Com\u00edn\",\"Ag\u00e8ncia Europea Medicaments\"],\"articleSection\":[\"FEFAC\",\"AFB\",\"AFET\",\"AFELL\",\"AGFE\",\"Pol\u00edtica sanit\u00e0ria\"],\"inLanguage\":\"ca\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/fefac.cat\\\/empresarial\\\/barcelona-s-una-candidatura-imbatible-com-a-seu\\\/\",\"url\":\"https:\\\/\\\/fefac.cat\\\/empresarial\\\/barcelona-s-una-candidatura-imbatible-com-a-seu\\\/\",\"name\":\"Barcelona \u00e9s una candidatura \u201cimbatible\u201d com a seu de l\u2019Ag\u00e8ncia Europea del Medicament - FEFAC\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fefac.cat\\\/empresarial\\\/#website\"},\"datePublished\":\"2017-09-12T13:42:59+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/fefac.cat\\\/empresarial\\\/#\\\/schema\\\/person\\\/03012b2506772bd65738ce781a3947f7\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/fefac.cat\\\/empresarial\\\/barcelona-s-una-candidatura-imbatible-com-a-seu\\\/#breadcrumb\"},\"inLanguage\":\"ca\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/fefac.cat\\\/empresarial\\\/barcelona-s-una-candidatura-imbatible-com-a-seu\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/fefac.cat\\\/empresarial\\\/barcelona-s-una-candidatura-imbatible-com-a-seu\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/fefac.cat\\\/empresarial\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Barcelona \u00e9s una candidatura \u201cimbatible\u201d com a seu de l\u2019Ag\u00e8ncia Europea del Medicament\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/fefac.cat\\\/empresarial\\\/#website\",\"url\":\"https:\\\/\\\/fefac.cat\\\/empresarial\\\/\",\"name\":\"FEFAC\",\"description\":\"Federaci\u00f3 d&#039;Associacions de Farm\u00e0cies de Catalunya\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/fefac.cat\\\/empresarial\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ca\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/fefac.cat\\\/empresarial\\\/#\\\/schema\\\/person\\\/03012b2506772bd65738ce781a3947f7\",\"name\":\"qabh859\",\"url\":\"https:\\\/\\\/fefac.cat\\\/empresarial\\\/author\\\/qabh859\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Barcelona \u00e9s una candidatura \u201cimbatible\u201d com a seu de l\u2019Ag\u00e8ncia Europea del Medicament - FEFAC","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/fefac.cat\/empresarial\/barcelona-s-una-candidatura-imbatible-com-a-seu\/","og_locale":"ca_ES","og_type":"article","og_title":"Barcelona \u00e9s una candidatura \u201cimbatible\u201d com a seu de l\u2019Ag\u00e8ncia Europea del Medicament - FEFAC","og_description":"El conseller de Salut, Antoni Com&iacute;n, entrevistat recentment al programa Els Matins de TV3, opina&nbsp;que la decisi&oacute; sobre la ciutat que albergar&agrave; la seu de l&rsquo;Ag&egrave;ncia Europea del Medicament, que [&hellip;]","og_url":"https:\/\/fefac.cat\/empresarial\/barcelona-s-una-candidatura-imbatible-com-a-seu\/","og_site_name":"FEFAC","article_published_time":"2017-09-12T13:42:59+00:00","author":"qabh859","twitter_card":"summary_large_image","twitter_misc":{"Escrit per":"qabh859","Temps estimat de lectura":"4 minuts"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/fefac.cat\/empresarial\/barcelona-s-una-candidatura-imbatible-com-a-seu\/#article","isPartOf":{"@id":"https:\/\/fefac.cat\/empresarial\/barcelona-s-una-candidatura-imbatible-com-a-seu\/"},"author":{"name":"qabh859","@id":"https:\/\/fefac.cat\/empresarial\/#\/schema\/person\/03012b2506772bd65738ce781a3947f7"},"headline":"Barcelona \u00e9s una candidatura \u201cimbatible\u201d com a seu de l\u2019Ag\u00e8ncia Europea del Medicament","datePublished":"2017-09-12T13:42:59+00:00","mainEntityOfPage":{"@id":"https:\/\/fefac.cat\/empresarial\/barcelona-s-una-candidatura-imbatible-com-a-seu\/"},"wordCount":753,"keywords":["EMA","Com\u00edn","Ag\u00e8ncia Europea Medicaments"],"articleSection":["FEFAC","AFB","AFET","AFELL","AGFE","Pol\u00edtica sanit\u00e0ria"],"inLanguage":"ca"},{"@type":"WebPage","@id":"https:\/\/fefac.cat\/empresarial\/barcelona-s-una-candidatura-imbatible-com-a-seu\/","url":"https:\/\/fefac.cat\/empresarial\/barcelona-s-una-candidatura-imbatible-com-a-seu\/","name":"Barcelona \u00e9s una candidatura \u201cimbatible\u201d com a seu de l\u2019Ag\u00e8ncia Europea del Medicament - FEFAC","isPartOf":{"@id":"https:\/\/fefac.cat\/empresarial\/#website"},"datePublished":"2017-09-12T13:42:59+00:00","author":{"@id":"https:\/\/fefac.cat\/empresarial\/#\/schema\/person\/03012b2506772bd65738ce781a3947f7"},"breadcrumb":{"@id":"https:\/\/fefac.cat\/empresarial\/barcelona-s-una-candidatura-imbatible-com-a-seu\/#breadcrumb"},"inLanguage":"ca","potentialAction":[{"@type":"ReadAction","target":["https:\/\/fefac.cat\/empresarial\/barcelona-s-una-candidatura-imbatible-com-a-seu\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/fefac.cat\/empresarial\/barcelona-s-una-candidatura-imbatible-com-a-seu\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/fefac.cat\/empresarial\/"},{"@type":"ListItem","position":2,"name":"Barcelona \u00e9s una candidatura \u201cimbatible\u201d com a seu de l\u2019Ag\u00e8ncia Europea del Medicament"}]},{"@type":"WebSite","@id":"https:\/\/fefac.cat\/empresarial\/#website","url":"https:\/\/fefac.cat\/empresarial\/","name":"FEFAC","description":"Federaci\u00f3 d&#039;Associacions de Farm\u00e0cies de Catalunya","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/fefac.cat\/empresarial\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ca"},{"@type":"Person","@id":"https:\/\/fefac.cat\/empresarial\/#\/schema\/person\/03012b2506772bd65738ce781a3947f7","name":"qabh859","url":"https:\/\/fefac.cat\/empresarial\/author\/qabh859\/"}]}},"_links":{"self":[{"href":"https:\/\/fefac.cat\/empresarial\/wp-json\/wp\/v2\/posts\/8547","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fefac.cat\/empresarial\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fefac.cat\/empresarial\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fefac.cat\/empresarial\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/fefac.cat\/empresarial\/wp-json\/wp\/v2\/comments?post=8547"}],"version-history":[{"count":0,"href":"https:\/\/fefac.cat\/empresarial\/wp-json\/wp\/v2\/posts\/8547\/revisions"}],"wp:attachment":[{"href":"https:\/\/fefac.cat\/empresarial\/wp-json\/wp\/v2\/media?parent=8547"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fefac.cat\/empresarial\/wp-json\/wp\/v2\/categories?post=8547"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fefac.cat\/empresarial\/wp-json\/wp\/v2\/tags?post=8547"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}